{"id":989012,"date":"2023-12-19T15:43:57","date_gmt":"2023-12-19T14:43:57","guid":{"rendered":"https:\/\/pepjoanjoies.rwdesarrollos.es\/catalegs\/sin categor\u00eda\/collar-bolita-plana-con-cadenita-plata\/"},"modified":"2023-12-19T15:43:57","modified_gmt":"2023-12-19T14:43:57","slug":"collar-bolita-plana-con-cadenita-plata","status":"publish","type":"product","link":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/","title":{"rendered":"COLLAR BOLITA PLANA CON CADENITA PLATA"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">Medidas c\u00edrculo : 2cm aprox total collar 42cm + 3cm alargador<\/div>\n<p><!-- .vgblk-rw-wrapper --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medidas c\u00edrculo : 2cm aprox total collar 42cm + 3cm alargador<\/p>\n","protected":false},"featured_media":988557,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[88],"product_tag":[],"class_list":["post-989012","product","type-product","status-publish","has-post-thumbnail","product_cat-bolita-plana","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies\" \/>\n<meta property=\"og:description\" content=\"Medidas c\u00edrculo : 2cm aprox total collar 42cm + 3cm alargador\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/\" \/>\n<meta property=\"og:site_name\" content=\"Pep Joan Joies\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pepjoanjoies\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pepjoanjoies.com\/wp-content\/uploads\/2023\/12\/8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1367\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/\",\"url\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/\",\"name\":\"COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies\",\"isPartOf\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg\",\"datePublished\":\"2023-12-19T14:43:57+00:00\",\"dateModified\":\"2023-12-19T14:43:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage\",\"url\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg\",\"contentUrl\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg\",\"width\":1367,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logos\",\"item\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/tienda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COLLAR BOLITA PLANA CON CADENITA PLATA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#website\",\"url\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/\",\"name\":\"Pep Joan Joies\",\"description\":\"Joies artesanals\",\"publisher\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#organization\",\"name\":\"Pep Joan Joies\",\"url\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2020\/02\/logotip_pj_joies-1__1___1_-removebg-preview.png\",\"contentUrl\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2020\/02\/logotip_pj_joies-1__1___1_-removebg-preview.png\",\"width\":960,\"height\":246,\"caption\":\"Pep Joan Joies\"},\"image\":{\"@id\":\"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pepjoanjoies\/\",\"https:\/\/www.instagram.com\/pepjoanjoies\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/","og_locale":"es_ES","og_type":"article","og_title":"COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies","og_description":"Medidas c\u00edrculo : 2cm aprox total collar 42cm + 3cm alargador","og_url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/","og_site_name":"Pep Joan Joies","article_publisher":"https:\/\/www.facebook.com\/pepjoanjoies\/","og_image":[{"width":1367,"height":2048,"url":"https:\/\/www.pepjoanjoies.com\/wp-content\/uploads\/2023\/12\/8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/","url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/","name":"COLLAR BOLITA PLANA CON CADENITA PLATA - Pep Joan Joies","isPartOf":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage"},"image":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage"},"thumbnailUrl":"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg","datePublished":"2023-12-19T14:43:57+00:00","dateModified":"2023-12-19T14:43:57+00:00","breadcrumb":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#primaryimage","url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg","contentUrl":"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2023\/12\/8.jpg","width":1367,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/catalegs\/bolita-plana\/collar-bolita-plana-con-cadenita-plata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logos","item":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"COLLAR BOLITA PLANA CON CADENITA PLATA"}]},{"@type":"WebSite","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#website","url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/","name":"Pep Joan Joies","description":"Joies artesanals","publisher":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#organization","name":"Pep Joan Joies","url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2020\/02\/logotip_pj_joies-1__1___1_-removebg-preview.png","contentUrl":"https:\/\/pepjoanjoies.rwdesarrollos.es\/wp-content\/uploads\/2020\/02\/logotip_pj_joies-1__1___1_-removebg-preview.png","width":960,"height":246,"caption":"Pep Joan Joies"},"image":{"@id":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pepjoanjoies\/","https:\/\/www.instagram.com\/pepjoanjoies\/"]}]}},"_links":{"self":[{"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/product\/989012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/comments?post=989012"}],"version-history":[{"count":0,"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/product\/989012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/media\/988557"}],"wp:attachment":[{"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/media?parent=989012"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/product_cat?post=989012"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pepjoanjoies.rwdesarrollos.es\/es\/wp-json\/wp\/v2\/product_tag?post=989012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}